{"id":125737,"date":"2023-10-10T00:00:00","date_gmt":"2023-10-10T00:00:00","guid":{"rendered":"https:\/\/uwm.edu\/news\/?p=125737"},"modified":"2023-10-09T09:04:34","modified_gmt":"2023-10-09T14:04:34","slug":"search-screen-committee-director-lubar-entrepreneurship-center-10-10-2023","status":"publish","type":"post","link":"https:\/\/uwm.edu\/news\/search-screen-committee-director-lubar-entrepreneurship-center-10-10-2023\/","title":{"rendered":"Search &amp; Screen Committee \u2013 Director, Lubar Entrepreneurship Center, 10\/10\/2023"},"content":{"rendered":"<p><strong>Search &amp; Screen Committee \u2013 Director, Lubar Entrepreneurship Center<\/strong><br \/>\nhttps:\/\/teams.microsoft.com\/l\/meetup-join\/19%3ameeting_YmYyZWEwNDQtMzE0Ny00Mzc5LTkzYjYtMzYzYmU1MzA3Nzhk%40thread.v2\/0?context=%7b%22Tid%22%3a%220bca7ac3-fcb6-4efd-89eb-6de97603cf21%22%2c%22Oid%22%3a%225b283572-6068-4fdf-a55c-cea394e09ea3%22%7d Meeting ID: 215 166 082 41  Passcode: E5fgFP  Download Teams | Join on the web Or call in (audio only)  +1 414-253-8850,,699150827#   United States, Milwaukee  Phone Conference ID: 699 150 827#, 10:50 am<br \/>\n<strong> Purpose of Meeting: <\/strong>Open Session Business: none<br \/>\nClosed Session Business: to interview candidates<br \/>\n<strong>Contact:<\/strong> Yulia Siverikova, <a href=\"mailto:siveriko@uwm.edu\">siveriko@uwm.edu<\/a>, (414) 251-5239.<br \/>\n<strong>This meeting may go into closed session, per state statute:<\/strong> <br \/>Wis. Stat. sec. 19.85(1)(c) \t<br \/>Considering employment, promotion, compensation or performance evaluation data of any public employee over which the governmental body has jurisdiction or exercises responsibility., Wis. Stat. sec. 19.85(1)(f)     <br \/>Considering financial, medical, social or personal histories or disciplinary data of specific persons, preliminary consideration of specific personnel problems or the investigation of charges against specific persons.<\/p>\n<p>This meeting will reconvene in open session.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Search &amp; Screen Committee \u2013 Director, Lubar Entrepreneurship Center https:\/\/teams.microsoft.com\/l\/meetup-join\/19%3ameeting_YmYyZWEwNDQtMzE0Ny00Mzc5LTkzYjYtMzYzYmU1MzA3Nzhk%40thread.v2\/0?context=%7b%22Tid%22%3a%220bca7ac3-fcb6-4efd-89eb-6de97603cf21%22%2c%22Oid%22%3a%225b283572-6068-4fdf-a55c-cea394e09ea3%22%7d Meeting ID: 215 166 082 41 Passcode: E5fgFP Download Teams | Join on the web Or call in (audio only) +1 414-253-8850,,699150827# United States, Milwaukee Phone Conference ID: 699 150 827#, 10:50 am Purpose of Meeting: Open Session Business: none Closed Session Business: to interview [&hellip;]<\/p>\n","protected":false},"author":40008,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","uwm_wg_additional_authors":[]},"categories":[197],"tags":[],"section":[],"display_categories":[],"related-coverage":[],"uwmnews-feed":[],"class_list":["post-125737","post","type-post","status-publish","format-standard","hentry","category-open-meeting-notices"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.5 (Yoast SEO v27.5) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Search &amp; Screen Committee \u2013 Director, Lubar Entrepreneurship Center, 10\/10\/2023<\/title>\n<meta name=\"description\" content=\"Search &amp; Screen Committee \u2013 Director, Lubar Entrepreneurship Center\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/uwm.edu\/news\/search-screen-committee-director-lubar-entrepreneurship-center-10-10-2023\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Search &amp; Screen Committee \u2013 Director, Lubar Entrepreneurship Center, 10\/10\/2023\" \/>\n<meta property=\"og:description\" content=\"Search &amp; Screen Committee \u2013 Director, Lubar Entrepreneurship Center\" \/>\n<meta property=\"og:url\" content=\"https:\/\/uwm.edu\/news\/search-screen-committee-director-lubar-entrepreneurship-center-10-10-2023\/\" \/>\n<meta property=\"og:site_name\" content=\"UWM REPORT\" \/>\n<meta property=\"article:published_time\" content=\"2023-10-10T00:00:00+00:00\" \/>\n<meta name=\"author\" content=\"UWM News\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@UWMNews\" \/>\n<meta name=\"twitter:site\" content=\"@UWMNews\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"UWM News\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/uwm.edu\\\/news\\\/search-screen-committee-director-lubar-entrepreneurship-center-10-10-2023\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/uwm.edu\\\/news\\\/search-screen-committee-director-lubar-entrepreneurship-center-10-10-2023\\\/\"},\"author\":{\"name\":\"UWM News\",\"@id\":\"https:\\\/\\\/uwm.edu\\\/news\\\/#\\\/schema\\\/person\\\/d72440401ec36965989bb00390105686\"},\"headline\":\"Search &amp; Screen Committee \u2013 Director, Lubar Entrepreneurship Center, 10\\\/10\\\/2023\",\"datePublished\":\"2023-10-10T00:00:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/uwm.edu\\\/news\\\/search-screen-committee-director-lubar-entrepreneurship-center-10-10-2023\\\/\"},\"wordCount\":173,\"publisher\":{\"@id\":\"https:\\\/\\\/uwm.edu\\\/news\\\/#organization\"},\"articleSection\":[\"Open Meeting Notices\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/uwm.edu\\\/news\\\/search-screen-committee-director-lubar-entrepreneurship-center-10-10-2023\\\/\",\"url\":\"https:\\\/\\\/uwm.edu\\\/news\\\/search-screen-committee-director-lubar-entrepreneurship-center-10-10-2023\\\/\",\"name\":\"Search &amp; Screen Committee \u2013 Director, Lubar Entrepreneurship Center, 10\\\/10\\\/2023\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/uwm.edu\\\/news\\\/#website\"},\"datePublished\":\"2023-10-10T00:00:00+00:00\",\"description\":\"Search &amp; Screen Committee \u2013 Director, Lubar Entrepreneurship Center\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/uwm.edu\\\/news\\\/search-screen-committee-director-lubar-entrepreneurship-center-10-10-2023\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/uwm.edu\\\/news\\\/search-screen-committee-director-lubar-entrepreneurship-center-10-10-2023\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/uwm.edu\\\/news\\\/search-screen-committee-director-lubar-entrepreneurship-center-10-10-2023\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/uwm.edu\\\/news\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Search &amp; Screen Committee \u2013 Director, Lubar Entrepreneurship Center, 10\\\/10\\\/2023\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/uwm.edu\\\/news\\\/#website\",\"url\":\"https:\\\/\\\/uwm.edu\\\/news\\\/\",\"name\":\"UWM REPORT\",\"description\":\"News from the University of Wisconsin - Milwaukee\",\"publisher\":{\"@id\":\"https:\\\/\\\/uwm.edu\\\/news\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/uwm.edu\\\/news\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/uwm.edu\\\/news\\\/#organization\",\"name\":\"University of Wisconsin-Milwaukee\",\"url\":\"https:\\\/\\\/uwm.edu\\\/news\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/uwm.edu\\\/news\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/uwm.edu\\\/news\\\/wp-content\\\/uploads\\\/sites\\\/41\\\/2017\\\/02\\\/uwm-seo-logo.jpg\",\"contentUrl\":\"https:\\\/\\\/uwm.edu\\\/news\\\/wp-content\\\/uploads\\\/sites\\\/41\\\/2017\\\/02\\\/uwm-seo-logo.jpg\",\"width\":225,\"height\":224,\"caption\":\"University of Wisconsin-Milwaukee\"},\"image\":{\"@id\":\"https:\\\/\\\/uwm.edu\\\/news\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/UWMNews\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/uwm.edu\\\/news\\\/#\\\/schema\\\/person\\\/d72440401ec36965989bb00390105686\",\"name\":\"UWM News\",\"url\":\"https:\\\/\\\/uwm.edu\\\/news\\\/author\\\/uwmnewsuwm-edu\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Search &amp; Screen Committee \u2013 Director, Lubar Entrepreneurship Center, 10\/10\/2023","description":"Search &amp; Screen Committee \u2013 Director, Lubar Entrepreneurship Center","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/uwm.edu\/news\/search-screen-committee-director-lubar-entrepreneurship-center-10-10-2023\/","og_locale":"en_US","og_type":"article","og_title":"Search &amp; Screen Committee \u2013 Director, Lubar Entrepreneurship Center, 10\/10\/2023","og_description":"Search &amp; Screen Committee \u2013 Director, Lubar Entrepreneurship Center","og_url":"https:\/\/uwm.edu\/news\/search-screen-committee-director-lubar-entrepreneurship-center-10-10-2023\/","og_site_name":"UWM REPORT","article_published_time":"2023-10-10T00:00:00+00:00","author":"UWM News","twitter_card":"summary_large_image","twitter_creator":"@UWMNews","twitter_site":"@UWMNews","twitter_misc":{"Written by":"UWM News","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/uwm.edu\/news\/search-screen-committee-director-lubar-entrepreneurship-center-10-10-2023\/#article","isPartOf":{"@id":"https:\/\/uwm.edu\/news\/search-screen-committee-director-lubar-entrepreneurship-center-10-10-2023\/"},"author":{"name":"UWM News","@id":"https:\/\/uwm.edu\/news\/#\/schema\/person\/d72440401ec36965989bb00390105686"},"headline":"Search &amp; Screen Committee \u2013 Director, Lubar Entrepreneurship Center, 10\/10\/2023","datePublished":"2023-10-10T00:00:00+00:00","mainEntityOfPage":{"@id":"https:\/\/uwm.edu\/news\/search-screen-committee-director-lubar-entrepreneurship-center-10-10-2023\/"},"wordCount":173,"publisher":{"@id":"https:\/\/uwm.edu\/news\/#organization"},"articleSection":["Open Meeting Notices"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/uwm.edu\/news\/search-screen-committee-director-lubar-entrepreneurship-center-10-10-2023\/","url":"https:\/\/uwm.edu\/news\/search-screen-committee-director-lubar-entrepreneurship-center-10-10-2023\/","name":"Search &amp; Screen Committee \u2013 Director, Lubar Entrepreneurship Center, 10\/10\/2023","isPartOf":{"@id":"https:\/\/uwm.edu\/news\/#website"},"datePublished":"2023-10-10T00:00:00+00:00","description":"Search &amp; Screen Committee \u2013 Director, Lubar Entrepreneurship Center","breadcrumb":{"@id":"https:\/\/uwm.edu\/news\/search-screen-committee-director-lubar-entrepreneurship-center-10-10-2023\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/uwm.edu\/news\/search-screen-committee-director-lubar-entrepreneurship-center-10-10-2023\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/uwm.edu\/news\/search-screen-committee-director-lubar-entrepreneurship-center-10-10-2023\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/uwm.edu\/news\/"},{"@type":"ListItem","position":2,"name":"Search &amp; Screen Committee \u2013 Director, Lubar Entrepreneurship Center, 10\/10\/2023"}]},{"@type":"WebSite","@id":"https:\/\/uwm.edu\/news\/#website","url":"https:\/\/uwm.edu\/news\/","name":"UWM REPORT","description":"News from the University of Wisconsin - Milwaukee","publisher":{"@id":"https:\/\/uwm.edu\/news\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/uwm.edu\/news\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/uwm.edu\/news\/#organization","name":"University of Wisconsin-Milwaukee","url":"https:\/\/uwm.edu\/news\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/uwm.edu\/news\/#\/schema\/logo\/image\/","url":"https:\/\/uwm.edu\/news\/wp-content\/uploads\/sites\/41\/2017\/02\/uwm-seo-logo.jpg","contentUrl":"https:\/\/uwm.edu\/news\/wp-content\/uploads\/sites\/41\/2017\/02\/uwm-seo-logo.jpg","width":225,"height":224,"caption":"University of Wisconsin-Milwaukee"},"image":{"@id":"https:\/\/uwm.edu\/news\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/UWMNews"]},{"@type":"Person","@id":"https:\/\/uwm.edu\/news\/#\/schema\/person\/d72440401ec36965989bb00390105686","name":"UWM News","url":"https:\/\/uwm.edu\/news\/author\/uwmnewsuwm-edu\/"}]}},"acf":[],"publishpress_future_action":{"enabled":false,"date":"2026-05-20 11:29:35","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/uwm.edu\/news\/wp-json\/wp\/v2\/posts\/125737","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/uwm.edu\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/uwm.edu\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/uwm.edu\/news\/wp-json\/wp\/v2\/users\/40008"}],"replies":[{"embeddable":true,"href":"https:\/\/uwm.edu\/news\/wp-json\/wp\/v2\/comments?post=125737"}],"version-history":[{"count":1,"href":"https:\/\/uwm.edu\/news\/wp-json\/wp\/v2\/posts\/125737\/revisions"}],"predecessor-version":[{"id":125738,"href":"https:\/\/uwm.edu\/news\/wp-json\/wp\/v2\/posts\/125737\/revisions\/125738"}],"wp:attachment":[{"href":"https:\/\/uwm.edu\/news\/wp-json\/wp\/v2\/media?parent=125737"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/uwm.edu\/news\/wp-json\/wp\/v2\/categories?post=125737"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/uwm.edu\/news\/wp-json\/wp\/v2\/tags?post=125737"},{"taxonomy":"section","embeddable":true,"href":"https:\/\/uwm.edu\/news\/wp-json\/wp\/v2\/section?post=125737"},{"taxonomy":"display_categories","embeddable":true,"href":"https:\/\/uwm.edu\/news\/wp-json\/wp\/v2\/display_categories?post=125737"},{"taxonomy":"related-coverage","embeddable":true,"href":"https:\/\/uwm.edu\/news\/wp-json\/wp\/v2\/related-coverage?post=125737"},{"taxonomy":"uwmnews-feed","embeddable":true,"href":"https:\/\/uwm.edu\/news\/wp-json\/wp\/v2\/uwmnews-feed?post=125737"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}