{"id":2736,"date":"2018-12-27T12:06:00","date_gmt":"2018-12-27T18:06:00","guid":{"rendered":"https:\/\/uwm.edu\/geography\/?post_type=tribe_events&#038;p=2736"},"modified":"2018-12-27T12:06:00","modified_gmt":"2018-12-27T18:06:00","slug":"research-symposium","status":"publish","type":"tribe_events","link":"https:\/\/uwm.edu\/geography\/event\/research-symposium\/","title":{"rendered":"Research Symposium"},"content":{"rendered":"<p>Join us for the Geography 600 Research Symposium all-day event.<br \/>\nAmerican Geographical Society Library, 3rd floor, Golda Meir Library<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Join us for the Geography 600 Research Symposium all-day event. American Geographical Society Library, 3rd floor, Golda Meir Library<\/p>\n","protected":false},"author":30,"featured_media":0,"template":"","meta":{"_acf_changed":false,"_tribe_events_status":"","_tribe_events_status_reason":"","_tribe_events_is_hybrid":"","_tribe_events_is_virtual":"","_tribe_events_virtual_video_source":"","_tribe_events_virtual_embed_video":"","_tribe_events_virtual_linked_button_text":"","_tribe_events_virtual_linked_button":"","_tribe_events_virtual_show_embed_at":"","_tribe_events_virtual_show_embed_to":[],"_tribe_events_virtual_show_on_event":"","_tribe_events_virtual_show_on_views":"","_tribe_events_virtual_url":"","footnotes":"","uwm_wg_additional_authors":[]},"tags":[],"tribe_events_cat":[13],"class_list":["post-2736","tribe_events","type-tribe_events","status-publish","hentry","tribe_events_cat-geography-colloquia","cat_geography-colloquia"],"uwm_unpublish_requested":false,"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Geography<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/uwm.edu\/geography\/event\/research-symposium\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Research Symposium\" \/>\n<meta property=\"og:description\" content=\"Join us for the Geography 600 Research Symposium all-day event. American Geographical Society Library, 3rd floor, Golda Meir Library\" \/>\n<meta property=\"og:url\" content=\"https:\/\/uwm.edu\/geography\/event\/research-symposium\/\" \/>\n<meta property=\"og:site_name\" content=\"Geography\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/uwm.edu\\\/geography\\\/event\\\/research-symposium\\\/\",\"url\":\"https:\\\/\\\/uwm.edu\\\/geography\\\/event\\\/research-symposium\\\/\",\"name\":\"Research Symposium - Geography\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/uwm.edu\\\/geography\\\/#website\"},\"datePublished\":\"2018-12-27T18:06:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/uwm.edu\\\/geography\\\/event\\\/research-symposium\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/uwm.edu\\\/geography\\\/event\\\/research-symposium\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/uwm.edu\\\/geography\\\/event\\\/research-symposium\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/uwm.edu\\\/geography\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Events\",\"item\":\"https:\\\/\\\/uwm.edu\\\/geography\\\/events\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Research Symposium\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/uwm.edu\\\/geography\\\/#website\",\"url\":\"https:\\\/\\\/uwm.edu\\\/geography\\\/\",\"name\":\"Geography\",\"description\":\"UW-Milwaukee\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/uwm.edu\\\/geography\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Geography","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/uwm.edu\/geography\/event\/research-symposium\/","og_locale":"en_US","og_type":"article","og_title":"Research Symposium","og_description":"Join us for the Geography 600 Research Symposium all-day event. American Geographical Society Library, 3rd floor, Golda Meir Library","og_url":"https:\/\/uwm.edu\/geography\/event\/research-symposium\/","og_site_name":"Geography","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/uwm.edu\/geography\/event\/research-symposium\/","url":"https:\/\/uwm.edu\/geography\/event\/research-symposium\/","name":"Research Symposium - Geography","isPartOf":{"@id":"https:\/\/uwm.edu\/geography\/#website"},"datePublished":"2018-12-27T18:06:00+00:00","breadcrumb":{"@id":"https:\/\/uwm.edu\/geography\/event\/research-symposium\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/uwm.edu\/geography\/event\/research-symposium\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/uwm.edu\/geography\/event\/research-symposium\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/uwm.edu\/geography\/"},{"@type":"ListItem","position":2,"name":"Events","item":"https:\/\/uwm.edu\/geography\/events\/"},{"@type":"ListItem","position":3,"name":"Research Symposium"}]},{"@type":"WebSite","@id":"https:\/\/uwm.edu\/geography\/#website","url":"https:\/\/uwm.edu\/geography\/","name":"Geography","description":"UW-Milwaukee","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/uwm.edu\/geography\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"acf":[],"_links":{"self":[{"href":"https:\/\/uwm.edu\/geography\/wp-json\/wp\/v2\/tribe_events\/2736","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/uwm.edu\/geography\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"https:\/\/uwm.edu\/geography\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"https:\/\/uwm.edu\/geography\/wp-json\/wp\/v2\/users\/30"}],"version-history":[{"count":1,"href":"https:\/\/uwm.edu\/geography\/wp-json\/wp\/v2\/tribe_events\/2736\/revisions"}],"predecessor-version":[{"id":2737,"href":"https:\/\/uwm.edu\/geography\/wp-json\/wp\/v2\/tribe_events\/2736\/revisions\/2737"}],"wp:attachment":[{"href":"https:\/\/uwm.edu\/geography\/wp-json\/wp\/v2\/media?parent=2736"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/uwm.edu\/geography\/wp-json\/wp\/v2\/tags?post=2736"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"https:\/\/uwm.edu\/geography\/wp-json\/wp\/v2\/tribe_events_cat?post=2736"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}