{"id":1579,"date":"2025-10-23T12:31:21","date_gmt":"2025-10-23T17:31:21","guid":{"rendered":"https:\/\/uwm.edu\/academicaffairs\/?page_id=1579"},"modified":"2025-10-23T12:31:22","modified_gmt":"2025-10-23T17:31:22","slug":"physical-therapy-dpt","status":"publish","type":"page","link":"https:\/\/uwm.edu\/academicaffairs\/resources\/professional-licensure-disclosures\/health-care-programs\/physical-therapy-dpt\/","title":{"rendered":"Physical Therapy, DPT"},"content":{"rendered":"\n<div class=\"uwm-l-row\">\n<div class=\"uwm-l-col\">\n<p>The Doctor of Physical Therapy program is accredited by the <a href=\"https:\/\/www.capteonline.org\/\">Commission on Accreditation in Physical Therapy Education (CAPTE)<\/a> and meets the educational requirements to become licensed in any US state. Completion of the degree does not automatically result in licensure in any state, including Wisconsin. However, students graduating from the program are eligible to sit for the National Physical Therapy Examination (NPTE) through the <a href=\"https:\/\/www.fsbpt.org\/\">Federation of State Boards of Physical Therapy (FSBPT)<\/a>.<\/p>\n\n\n\n<div class=\"uwm-p-card uwm-u-mb-40\"><div class=\"uwm-p-card--body\"><div class=\"uwm-p-card--content\">\n<h3 class=\"wp-block-heading size-h5\" id=\"h-meets-requirements\">Meets Requirements<\/h3>\n\n\n\n<div class=\"uwm-l-row\">\n<div class=\"uwm-l-col\">\n<ul class=\"wp-block-list size-p-sm uwm-c-list--cleanlist\">\n<li>Alabama (AL)<\/li>\n\n\n\n<li>Alaska (AK)<\/li>\n\n\n\n<li>Arizona (AZ)<\/li>\n\n\n\n<li>Arkansas (AR)<\/li>\n\n\n\n<li>California (CA)<\/li>\n\n\n\n<li>Colorado (CO)<\/li>\n\n\n\n<li>Connecticut (CT)<\/li>\n\n\n\n<li>Delaware (DE)<\/li>\n\n\n\n<li>District of Columbia (DC)<\/li>\n\n\n\n<li>Florida (FL)<\/li>\n\n\n\n<li>Georgia (GA)<\/li>\n\n\n\n<li>Hawaii (HI)<\/li>\n\n\n\n<li>Idaho (ID)<\/li>\n\n\n\n<li>Illinois (IL)<\/li>\n\n\n\n<li>Indiana (IN)<\/li>\n\n\n\n<li>Iowa (IA)<\/li>\n\n\n\n<li>Kansas (KS)<\/li>\n\n\n\n<li>Kentucky (KY)<\/li>\n\n\n\n<li>Louisiana (LA)<\/li>\n\n\n\n<li>Maine (ME)<\/li>\n<\/ul>\n<\/div>\n\n\n\n<div class=\"uwm-l-col\">\n<ul class=\"wp-block-list size-p-sm uwm-c-list--cleanlist\">\n<li>Maryland (MD)<\/li>\n\n\n\n<li>Massachusetts (MA)<\/li>\n\n\n\n<li>Michigan (MI)<\/li>\n\n\n\n<li>Minnesota (MN)<\/li>\n\n\n\n<li>Mississippi (MS)<\/li>\n\n\n\n<li>Missouri (MO)<\/li>\n\n\n\n<li>Montana (MT)<\/li>\n\n\n\n<li>Nebraska (NE)<\/li>\n\n\n\n<li>Nevada (NV)<\/li>\n\n\n\n<li>New Hampshire (NH)<\/li>\n\n\n\n<li>New Jersey (NJ)<\/li>\n\n\n\n<li>New Mexico (NM)<\/li>\n\n\n\n<li>New York (NY)<\/li>\n\n\n\n<li>North Carolina (NC)<\/li>\n\n\n\n<li>North Dakota (ND)<\/li>\n\n\n\n<li>Ohio (OH)<\/li>\n\n\n\n<li>Oklahoma (OK)<\/li>\n\n\n\n<li>Oregon (OR)<\/li>\n\n\n\n<li>Pennsylvania (PA)<\/li>\n<\/ul>\n<\/div>\n\n\n\n<div class=\"uwm-l-col\">\n<ul class=\"wp-block-list size-p-sm uwm-c-list--cleanlist\">\n<li>Rhode Island (RI)<\/li>\n\n\n\n<li>South Carolina (SC)<\/li>\n\n\n\n<li>South Dakota (SD)<\/li>\n\n\n\n<li>Tennessee (TN)<\/li>\n\n\n\n<li>Texas (TX)<\/li>\n\n\n\n<li>Utah (UT)<\/li>\n\n\n\n<li>Vermont (VT)<\/li>\n\n\n\n<li>Virginia (VA)<\/li>\n\n\n\n<li>Washington (WA)<\/li>\n\n\n\n<li>West Virginia (WV)<\/li>\n\n\n\n<li>Wisconsin (WI)<\/li>\n\n\n\n<li>Wyoming (WY)<\/li>\n<\/ul>\n\n\n\n<h5 class=\"wp-block-heading size-h6 uwm-u-mt-30 uwm-u-mb-0\" id=\"h-us-territories\"><strong>US Territories<\/strong><\/h5>\n\n\n\n<ul class=\"wp-block-list size-p-sm uwm-c-list--cleanlist\">\n<li>American Samoa (AS)<\/li>\n\n\n\n<li>Guam (GU)<\/li>\n\n\n\n<li>Northern Mariana Islands (MP)<\/li>\n\n\n\n<li>Puerto Rico (PR)<\/li>\n\n\n\n<li>Virgin Islands (VI)<br><\/li>\n<\/ul>\n<\/div>\n<\/div>\n<\/div><\/div><\/div>\n\n\n\n<div class=\"uwm-p-card uwm-u-mb-40\"><div class=\"uwm-p-card--body\"><div class=\"uwm-p-card--content\">\n<h2 class=\"wp-block-heading size-h5\" id=\"h-does-not-meet-requirements\">Does Not Meet Requirements<\/h2>\n\n\n\n<p>N\/A<\/p>\n<\/div><\/div><\/div>\n<\/div>\n\n\n\n<div class=\"uwm-l-col uwm-l-col--4 uwm-l-offset--1\"><div class=\"content_block\" id=\"custom_post_widget-215\"><nav aria-label=\"Sidebar\" class=\"uwm-p-navigation-list uwm-p-navigation-list--gold-border \"><div class=\"uwm-p-navigation-list--title\"><a href=\"https:\/\/uwm.edu\/academicaffairs\/resources\/\">Resources<\/a><\/div><ul><li><a href=\"https:\/\/uwm.edu\/academicaffairs\/resources\/academic-program-resources\/\">Academic Program Resources<\/a><\/li><li><a href=\"https:\/\/uwm.edu\/academicaffairs\/resources\/accreditation\/\">Accreditation<\/a><\/li><li><a href=\"https:\/\/uwm.edu\/academicaffairs\/resources\/department-chair-resources\/\">Department Chair Resources<\/a><\/li><li><a href=\"https:\/\/uwm.edu\/academicaffairs\/resources\/distinguished-professors\/\">Distinguished Professors<\/a><\/li><li><a href=\"https:\/\/uwm.edu\/academicaffairs\/resources\/microcredentials\/\">Microcredentials<\/a><\/li><li><a href=\"https:\/\/uwm.edu\/academicaffairs\/resources\/office-of-dual-enrollment\/\">Office of Dual Enrollment<\/a><\/li><li><a href=\"https:\/\/uwm.edu\/academicaffairs\/resources\/resources-for-instructors\/\">Resources for Instructors<\/a><\/li><li><a href=\"https:\/\/uwm.edu\/academicaffairs\/resources\/planning\/\">Planning<\/a><\/li><li><a href=\"https:\/\/uwm.edu\/academicaffairs\/resources\/professional-licensure-disclosures\/\">Professional Licensure Disclosures<\/a><ul><li><a href=\"https:\/\/uwm.edu\/academicaffairs\/resources\/professional-licensure-disclosures\/accounting-programs\/\">Accounting Programs<\/a><\/li><li><a href=\"https:\/\/uwm.edu\/academicaffairs\/resources\/professional-licensure-disclosures\/architecture-programs\/\">Architecture Programs<\/a><\/li><li><a href=\"https:\/\/uwm.edu\/academicaffairs\/resources\/professional-licensure-disclosures\/education-programs\/\">Education Programs<\/a><\/li><li><a href=\"https:\/\/uwm.edu\/academicaffairs\/resources\/professional-licensure-disclosures\/health-care-programs\/\">Health Care Programs<\/a><ul><li><a href=\"https:\/\/uwm.edu\/academicaffairs\/resources\/professional-licensure-disclosures\/health-care-programs\/athletic-training-ms\/\">Athletic Training, MS<\/a><\/li><li><a href=\"https:\/\/uwm.edu\/academicaffairs\/resources\/professional-licensure-disclosures\/health-care-programs\/diagnostic-medical-sonography-bs\/\">Diagnostic Medical Sonography, BS<\/a><\/li><li><a href=\"https:\/\/uwm.edu\/academicaffairs\/resources\/professional-licensure-disclosures\/health-care-programs\/medical-lab-science-bs\/\">Medical Lab Science, BS<\/a><\/li><li><a href=\"https:\/\/uwm.edu\/academicaffairs\/resources\/professional-licensure-disclosures\/health-care-programs\/occupational-therapy-ms\/\">Occupational Therapy, MS<\/a><\/li><li><a class=\"current\" href=\"https:\/\/uwm.edu\/academicaffairs\/resources\/professional-licensure-disclosures\/health-care-programs\/physical-therapy-dpt\/\"><span aria-current=\"page\">Physical Therapy, DPT<\/span><\/a><\/li><li><a href=\"https:\/\/uwm.edu\/academicaffairs\/resources\/professional-licensure-disclosures\/health-care-programs\/radiologic-technology-bs\/\">Radiologic Technology, BS<\/a><\/li><li><a href=\"https:\/\/uwm.edu\/academicaffairs\/resources\/professional-licensure-disclosures\/health-care-programs\/speech-language-pathology-ms\/\">Speech Language Pathology, MS<\/a><\/li><\/ul><\/li><li><a href=\"https:\/\/uwm.edu\/academicaffairs\/resources\/professional-licensure-disclosures\/nursing-programs\/\">Nursing Programs<\/a><\/li><li><a href=\"https:\/\/uwm.edu\/academicaffairs\/resources\/professional-licensure-disclosures\/psychology-programs\/\">Psychology Programs<\/a><\/li><li><a href=\"https:\/\/uwm.edu\/academicaffairs\/resources\/professional-licensure-disclosures\/school-library-programs\/\">School Library Programs<\/a><\/li><li><a href=\"https:\/\/uwm.edu\/academicaffairs\/resources\/professional-licensure-disclosures\/social-work-programs\/\">Social Work Programs<\/a><\/li><\/ul><\/li><\/ul><\/nav>\n\n\n<p><\/p>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":29,"featured_media":0,"parent":1560,"menu_order":4,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":"","uwm_wg_additional_authors":[]},"class_list":["post-1579","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.5 (Yoast SEO v27.5) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Academic Affairs<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/uwm.edu\/academicaffairs\/resources\/professional-licensure-disclosures\/health-care-programs\/physical-therapy-dpt\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Physical Therapy, DPT\" \/>\n<meta property=\"og:url\" content=\"https:\/\/uwm.edu\/academicaffairs\/resources\/professional-licensure-disclosures\/health-care-programs\/physical-therapy-dpt\/\" \/>\n<meta property=\"og:site_name\" content=\"Academic Affairs\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-23T17:31:22+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/uwm.edu\\\/academicaffairs\\\/resources\\\/professional-licensure-disclosures\\\/health-care-programs\\\/physical-therapy-dpt\\\/\",\"url\":\"https:\\\/\\\/uwm.edu\\\/academicaffairs\\\/resources\\\/professional-licensure-disclosures\\\/health-care-programs\\\/physical-therapy-dpt\\\/\",\"name\":\"Physical Therapy, DPT - Academic Affairs\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/uwm.edu\\\/academicaffairs\\\/#website\"},\"datePublished\":\"2025-10-23T17:31:21+00:00\",\"dateModified\":\"2025-10-23T17:31:22+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/uwm.edu\\\/academicaffairs\\\/resources\\\/professional-licensure-disclosures\\\/health-care-programs\\\/physical-therapy-dpt\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/uwm.edu\\\/academicaffairs\\\/resources\\\/professional-licensure-disclosures\\\/health-care-programs\\\/physical-therapy-dpt\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/uwm.edu\\\/academicaffairs\\\/resources\\\/professional-licensure-disclosures\\\/health-care-programs\\\/physical-therapy-dpt\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/uwm.edu\\\/academicaffairs\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Resources\",\"item\":\"https:\\\/\\\/uwm.edu\\\/academicaffairs\\\/resources\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Professional Licensure Disclosures\",\"item\":\"https:\\\/\\\/uwm.edu\\\/academicaffairs\\\/resources\\\/professional-licensure-disclosures\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Health Care Programs\",\"item\":\"https:\\\/\\\/uwm.edu\\\/academicaffairs\\\/resources\\\/professional-licensure-disclosures\\\/health-care-programs\\\/\"},{\"@type\":\"ListItem\",\"position\":5,\"name\":\"Physical Therapy, DPT\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/uwm.edu\\\/academicaffairs\\\/#website\",\"url\":\"https:\\\/\\\/uwm.edu\\\/academicaffairs\\\/\",\"name\":\"Academic Affairs\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/uwm.edu\\\/academicaffairs\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/uwm.edu\\\/academicaffairs\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/uwm.edu\\\/academicaffairs\\\/#organization\",\"name\":\"University of Wisconsin - Milwaukee\",\"url\":\"https:\\\/\\\/uwm.edu\\\/academicaffairs\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/uwm.edu\\\/academicaffairs\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/uwm.edu\\\/0template-webid2\\\/wp-content\\\/uploads\\\/sites\\\/541\\\/2020\\\/11\\\/uwm-seo-logo.jpg\",\"contentUrl\":\"https:\\\/\\\/uwm.edu\\\/0template-webid2\\\/wp-content\\\/uploads\\\/sites\\\/541\\\/2020\\\/11\\\/uwm-seo-logo.jpg\",\"width\":225,\"height\":224,\"caption\":\"University of Wisconsin - Milwaukee\"},\"image\":{\"@id\":\"https:\\\/\\\/uwm.edu\\\/academicaffairs\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Academic Affairs","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/uwm.edu\/academicaffairs\/resources\/professional-licensure-disclosures\/health-care-programs\/physical-therapy-dpt\/","og_locale":"en_US","og_type":"article","og_title":"Physical Therapy, DPT","og_url":"https:\/\/uwm.edu\/academicaffairs\/resources\/professional-licensure-disclosures\/health-care-programs\/physical-therapy-dpt\/","og_site_name":"Academic Affairs","article_modified_time":"2025-10-23T17:31:22+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/uwm.edu\/academicaffairs\/resources\/professional-licensure-disclosures\/health-care-programs\/physical-therapy-dpt\/","url":"https:\/\/uwm.edu\/academicaffairs\/resources\/professional-licensure-disclosures\/health-care-programs\/physical-therapy-dpt\/","name":"Physical Therapy, DPT - Academic Affairs","isPartOf":{"@id":"https:\/\/uwm.edu\/academicaffairs\/#website"},"datePublished":"2025-10-23T17:31:21+00:00","dateModified":"2025-10-23T17:31:22+00:00","breadcrumb":{"@id":"https:\/\/uwm.edu\/academicaffairs\/resources\/professional-licensure-disclosures\/health-care-programs\/physical-therapy-dpt\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/uwm.edu\/academicaffairs\/resources\/professional-licensure-disclosures\/health-care-programs\/physical-therapy-dpt\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/uwm.edu\/academicaffairs\/resources\/professional-licensure-disclosures\/health-care-programs\/physical-therapy-dpt\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/uwm.edu\/academicaffairs\/"},{"@type":"ListItem","position":2,"name":"Resources","item":"https:\/\/uwm.edu\/academicaffairs\/resources\/"},{"@type":"ListItem","position":3,"name":"Professional Licensure Disclosures","item":"https:\/\/uwm.edu\/academicaffairs\/resources\/professional-licensure-disclosures\/"},{"@type":"ListItem","position":4,"name":"Health Care Programs","item":"https:\/\/uwm.edu\/academicaffairs\/resources\/professional-licensure-disclosures\/health-care-programs\/"},{"@type":"ListItem","position":5,"name":"Physical Therapy, DPT"}]},{"@type":"WebSite","@id":"https:\/\/uwm.edu\/academicaffairs\/#website","url":"https:\/\/uwm.edu\/academicaffairs\/","name":"Academic Affairs","description":"","publisher":{"@id":"https:\/\/uwm.edu\/academicaffairs\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/uwm.edu\/academicaffairs\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/uwm.edu\/academicaffairs\/#organization","name":"University of Wisconsin - Milwaukee","url":"https:\/\/uwm.edu\/academicaffairs\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/uwm.edu\/academicaffairs\/#\/schema\/logo\/image\/","url":"https:\/\/uwm.edu\/0template-webid2\/wp-content\/uploads\/sites\/541\/2020\/11\/uwm-seo-logo.jpg","contentUrl":"https:\/\/uwm.edu\/0template-webid2\/wp-content\/uploads\/sites\/541\/2020\/11\/uwm-seo-logo.jpg","width":225,"height":224,"caption":"University of Wisconsin - Milwaukee"},"image":{"@id":"https:\/\/uwm.edu\/academicaffairs\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/uwm.edu\/academicaffairs\/wp-json\/wp\/v2\/pages\/1579","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/uwm.edu\/academicaffairs\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/uwm.edu\/academicaffairs\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/uwm.edu\/academicaffairs\/wp-json\/wp\/v2\/users\/29"}],"replies":[{"embeddable":true,"href":"https:\/\/uwm.edu\/academicaffairs\/wp-json\/wp\/v2\/comments?post=1579"}],"version-history":[{"count":1,"href":"https:\/\/uwm.edu\/academicaffairs\/wp-json\/wp\/v2\/pages\/1579\/revisions"}],"predecessor-version":[{"id":1580,"href":"https:\/\/uwm.edu\/academicaffairs\/wp-json\/wp\/v2\/pages\/1579\/revisions\/1580"}],"up":[{"embeddable":true,"href":"https:\/\/uwm.edu\/academicaffairs\/wp-json\/wp\/v2\/pages\/1560"}],"wp:attachment":[{"href":"https:\/\/uwm.edu\/academicaffairs\/wp-json\/wp\/v2\/media?parent=1579"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}